{"id":2805,"date":"2025-03-06T12:34:02","date_gmt":"2025-03-06T11:34:02","guid":{"rendered":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/"},"modified":"2025-03-06T12:34:02","modified_gmt":"2025-03-06T11:34:02","slug":"formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile","status":"publish","type":"mec-events","link":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/","title":{"rendered":"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile"},"content":{"rendered":"<p>formation de 3 jours pour le r\u00e9seau ALISO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>formation de 3 jours pour le r\u00e9seau ALISO<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-2805","mec-events","type-mec-events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau\" \/>\n<meta property=\"og:description\" content=\"formation de 3 jours pour le r\u00e9seau ALISO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/\" \/>\n<meta property=\"og:site_name\" content=\"Aliso R\u00e9seau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\\\/\",\"url\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\\\/\",\"name\":\"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#website\"},\"datePublished\":\"2025-03-06T11:34:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9venements\",\"item\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#website\",\"url\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/\",\"name\":\"Aliso R\u00e9seau\",\"description\":\"R\u00e9seau Creusois des acteurs du lien social\",\"publisher\":{\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#organization\",\"name\":\"Aliso R\u00e9seau\",\"url\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Logo-ALISO-Reseau-2.png\",\"contentUrl\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/01\\\/Logo-ALISO-Reseau-2.png\",\"width\":900,\"height\":970,\"caption\":\"Aliso R\u00e9seau\"},\"image\":{\"@id\":\"https:\\\/\\\/aliso.fr\\\/reseau\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/","og_locale":"fr_FR","og_type":"article","og_title":"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau","og_description":"formation de 3 jours pour le r\u00e9seau ALISO","og_url":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/","og_site_name":"Aliso R\u00e9seau","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/","url":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/","name":"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile - Aliso R\u00e9seau","isPartOf":{"@id":"https:\/\/aliso.fr\/reseau\/#website"},"datePublished":"2025-03-06T11:34:02+00:00","breadcrumb":{"@id":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aliso.fr\/reseau\/evenements\/formation-accueillir-et-accompagner-les-personnes-a-la-sante-mentale-fragile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aliso.fr\/reseau\/"},{"@type":"ListItem","position":2,"name":"\u00c9venements","item":"https:\/\/aliso.fr\/reseau\/evenements\/"},{"@type":"ListItem","position":3,"name":"Formation Accueillir et accompagner les personnes \u00e0 la sant\u00e9 mentale fragile"}]},{"@type":"WebSite","@id":"https:\/\/aliso.fr\/reseau\/#website","url":"https:\/\/aliso.fr\/reseau\/","name":"Aliso R\u00e9seau","description":"R\u00e9seau Creusois des acteurs du lien social","publisher":{"@id":"https:\/\/aliso.fr\/reseau\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aliso.fr\/reseau\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aliso.fr\/reseau\/#organization","name":"Aliso R\u00e9seau","url":"https:\/\/aliso.fr\/reseau\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aliso.fr\/reseau\/#\/schema\/logo\/image\/","url":"https:\/\/aliso.fr\/reseau\/wp-content\/uploads\/sites\/4\/2022\/01\/Logo-ALISO-Reseau-2.png","contentUrl":"https:\/\/aliso.fr\/reseau\/wp-content\/uploads\/sites\/4\/2022\/01\/Logo-ALISO-Reseau-2.png","width":900,"height":970,"caption":"Aliso R\u00e9seau"},"image":{"@id":"https:\/\/aliso.fr\/reseau\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/mec-events\/2805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/comments?post=2805"}],"wp:attachment":[{"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/media?parent=2805"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/tags?post=2805"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/aliso.fr\/reseau\/wp-json\/wp\/v2\/mec_category?post=2805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}